{"id":30047,"date":"2022-10-31T17:00:00","date_gmt":"2022-10-31T17:00:00","guid":{"rendered":"https:\/\/droix.net\/blogs\/droix-x4-review-with-video-nous-avons-une-nouvelle-android-tv-box\/"},"modified":"2025-09-12T12:27:16","modified_gmt":"2025-09-12T11:27:16","slug":"droix-x4-review-with-video-nous-avons-une-nouvelle-android-tv-box","status":"publish","type":"post","link":"https:\/\/droix.net\/blogs\/fr\/droix-x4-review-with-video-nous-avons-une-nouvelle-android-tv-box\/","title":{"rendered":"DroiX X4 Review with video - Nous avons une nouvelle Android TV box !"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Pour les fans de longue date de DroiX, vous savez que nous avons commenc\u00e9 il y a de nombreuses ann\u00e9es avec des <a href=\"https:\/\/droix.net\/blogs\/product-category\/android-gadgets\/android-tv-boxes\/\" target=\"_blank\" rel=\"noreferrer noopener\">bo\u00eetiers TV Android<\/a>. Cela fait un moment que nous n'avons pas publi\u00e9 notre propre mod\u00e8le, mais le temps est venu de changer cela avec notre \u00e9valuation du <a href=\"https:\/\/droix.eu\/fr\/product\/droix-x4\/\" target=\"_blank\" rel=\"noreferrer noopener\">DroiX X4<\/a>.<\/p>\n\n<h2 class=\"wp-block-heading\">Vid\u00e9o d'\u00e9valuation du DroiX X4<\/h2>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"DroiX X4 Android TV box review with discount - Android 11 IPTV media streaming and retro gaming box\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/lOWQwA9Q2qs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<h2 class=\"wp-block-heading\">Unboxing de la DroiX X4 Android TV box<\/h2>\n\n<p class=\"wp-block-paragraph\">Passons directement \u00e0 l'unboxing. En premier lieu, nous avons la <a href=\"https:\/\/droix.eu\/fr\/product\/droix-x4\/\" target=\"_blank\" rel=\"noreferrer noopener\">DroiX X4<\/a> Android TV box que nous pr\u00e9senterons plus en d\u00e9tail dans quelques instants.<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxed.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxed-1024x576.jpg\" alt=\"DroiX X4 Android TV box Unboxed\" class=\"wp-image-26982\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxed-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxed-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxed-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxed-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxed-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxed-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxed-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxed.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">DroiX X4 Android TV box Unboxed<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">En dessous se trouve un bloc d'alimentation, nous inclurons l'adaptateur correct pour votre pays. Ensuite, nous avons la <a href=\"https:\/\/droix.eu\/fr\/product\/droix-g10s-backlit-air-mouse\/\" target=\"_blank\" rel=\"noreferrer noopener\">souris DroiX G10S<\/a>, que nous pr\u00e9senterons plus en d\u00e9tail dans quelques instants. Un c\u00e2ble HDMI est pr\u00e9vu pour la connexion \u00e0 votre t\u00e9l\u00e9viseur ou \u00e0 votre moniteur. Enfin, une brochure d'initiation est disponible en anglais.<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxing.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxing-1024x576.jpg\" alt=\"DroiX X4 Unboxing\" class=\"wp-image-26987\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxing-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxing-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxing-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxing-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxing-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxing-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxing-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Unboxing.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">DroiX X4 Unboxing<\/figcaption><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\" id=\"h-overview-of-the-droix-x4\">Pr\u00e9sentation du DroiX X4<\/h2>\n\n<p class=\"wp-block-paragraph\">Le bo\u00eetier de streaming <a href=\"https:\/\/droix.eu\/fr\/product\/droix-x4\/\" target=\"_blank\" rel=\"noreferrer noopener\">DroiX X4<\/a> mesure environ 4,1 x 4,1 x 0,98 pouces (10,5 x 10,5 x 2,5 cm) et p\u00e8se 139 grammes.<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Dimensions.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Dimensions-1024x576.jpg\" alt=\"Dimensions du DroiX X4\" class=\"wp-image-26992\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Dimensions-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Dimensions-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Dimensions-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Dimensions-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Dimensions-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Dimensions-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Dimensions-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Dimensions.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Dimensions du DroiX X4<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Sur la face avant se trouve un \u00e9cran LCD qui affiche l'heure actuelle. Vous pouvez, si vous le souhaitez, l'assombrir ou le d\u00e9sactiver compl\u00e8tement dans les param\u00e8tres.<\/p>\n\n<p class=\"wp-block-paragraph\">Sur le c\u00f4t\u00e9 gauche se trouvent deux ports USB que vous pouvez utiliser pour des p\u00e9riph\u00e9riques et, \u00e0 c\u00f4t\u00e9, un emplacement pour carte micro SD pour un espace de stockage suppl\u00e9mentaire, par exemple.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Side.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Side-1024x576.jpg\" alt=\"DroiX X4 Vue lat&#xE9;rale\" class=\"wp-image-26997\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Side-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Side-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Side-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Side-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Side-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Side-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Side-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Side.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">DroiX X4 Vue lat\u00e9rale<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">\u00c0 l'arri\u00e8re se trouvent un port AV et un port optique pour l'audio. Il y a un port Ethernet 10\/100 pour les donn\u00e9es c\u00e2bl\u00e9es. Un port HDMI et une prise d'alimentation.<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Back.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Back-1024x576.jpg\" alt=\"DroiX X4 Vue arri&#xE8;re\" class=\"wp-image-27002\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Back-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Back-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Back-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Back-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Back-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Back-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Back-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Back.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">DroiX X4 Vue arri\u00e8re<\/figcaption><\/figure>\n<\/div>\n<h2 class=\"wp-block-heading\">Pr\u00e9sentation de la souris DroiX G10S Air Mouse<\/h2>\n\n<p class=\"wp-block-paragraph\">La souris a\u00e9rienne <a href=\"https:\/\/droix.eu\/fr\/product\/droix-g10s-backlit-air-mouse\/\" target=\"_blank\" rel=\"noreferrer noopener\">G10S<\/a> n\u00e9cessite deux piles AA et le dongle USB se trouve dans le compartiment des piles. Vous n'imaginez pas le nombre de personnes qui nous demandent o\u00f9 il se trouve \ud83d\ude42<\/p>\n\n<p class=\"wp-block-paragraph\">La t\u00e9l\u00e9commande G10S est r\u00e9tro\u00e9clair\u00e9e, ce qui vous permet de rep\u00e9rer les touches lorsque vous regardez la t\u00e9l\u00e9vision dans l'obscurit\u00e9. Vous disposez de tous les boutons habituels de la t\u00e9l\u00e9commande pour la navigation, les volumes, le d\u00e9filement vers le haut et vers le bas, le menu et le retour.<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-G10S-Air-Mouse.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-G10S-Air-Mouse-1024x576.jpg\" alt=\"DroiX X4 G10S Air Mouse\" class=\"wp-image-27007\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-G10S-Air-Mouse-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-G10S-Air-Mouse-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-G10S-Air-Mouse-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-G10S-Air-Mouse-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-G10S-Air-Mouse-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-G10S-Air-Mouse-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-G10S-Air-Mouse-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-G10S-Air-Mouse.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">DroiX X4 G10S Air Mouse<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Avec la <a href=\"https:\/\/droix.eu\/fr\/product\/droix-g10s-backlit-air-mouse\/\" target=\"_blank\" rel=\"noreferrer noopener\">souris pneumatique G10S<\/a>, vous pouvez agiter la main et faire semblant d'\u00eatre Harry Potter pour contr\u00f4ler le curseur de la souris \u00e0 l'\u00e9cran. \u00c9patez encore plus vos invit\u00e9s gr\u00e2ce au microphone int\u00e9gr\u00e9 et \u00e0 la recherche vocale sur les applications prises en charge.  <\/p>\n\n<p class=\"wp-block-paragraph\">Notez que vous pouvez utiliser les boutons via IR sans utiliser le dongle. En revanche, vous ne disposerez pas de la souris a\u00e9rienne ni des fonctions de recherche vocale.<\/p>\n\n<p class=\"wp-block-paragraph\">C'est une excellente t\u00e9l\u00e9commande et bien plus rapide que les anciennes t\u00e9l\u00e9commandes IR fournies avec les bo\u00eetiers android.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-droix-x4-technical-specifications\">Caract\u00e9ristiques techniques du DroiX X4<\/h2>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>UNIT\u00c9 CENTRALE<\/strong><\/td><td><a href=\"https:\/\/droix.eu\/fr\/product-attribute\/processor-cpu-model\/s905x4\/\" target=\"_blank\" rel=\"noreferrer noopener\">S905X4<\/a> Quad-Core ARM<\/td><\/tr><tr><td><strong>GPU<\/strong><\/td><td>ARM <a href=\"https:\/\/droix.eu\/fr\/product-attribute\/graphics-gpu-model\/mali-g31-mp2\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mali-G31 MP2<\/a><\/td><\/tr><tr><td><strong>RAM<\/strong><\/td><td>4GB <a href=\"https:\/\/droix.eu\/fr\/product-attribute\/memory-ram-technology\/ddr3\/\" target=\"_blank\" rel=\"noreferrer noopener\">DDR3<\/a><\/td><\/tr><tr><td><strong>STOCKAGE<\/strong><\/td><td>64GB<\/td><\/tr><tr><td><strong>CONNECTIVIT\u00c9<\/strong><\/td><td>WiFi 5<br\/>Bluetooth<\/td><\/tr><tr><td><strong>TEMP\u00c9RATURE MAXIMALE*<\/strong><\/td><td>50\u00b0C<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Caract\u00e9ristiques techniques du DroiX X4<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">*Temp\u00e9rature maximale mesur\u00e9e lors de l'ex\u00e9cution du test Antutu apr\u00e8s 10 minutes.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-system-benchmarks\">Benchmarks du syst\u00e8me<\/h2>\n\n<p class=\"wp-block-paragraph\">Poursuivant notre analyse du DroiX X4, nous allons maintenant effectuer quelques tests de performance. Vous pourrez utiliser les r\u00e9sultats pour comparer avec d'autres bo\u00eetiers TV Android.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-geekbench\">Geekbench<\/h3>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.geekbench.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Geekbench <\/a>effectue une s\u00e9rie de tests sur les appareils pour en mesurer les performances. Nous utilisons le benchmark CPU qui teste les performances mono et multi-c\u0153urs.<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Geekbench-Result.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Geekbench-Result-1024x576.jpg\" alt=\"R&#xE9;sultat Geekbench\" class=\"wp-image-27012\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Geekbench-Result-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Geekbench-Result-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Geekbench-Result-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Geekbench-Result-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Geekbench-Result-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Geekbench-Result-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Geekbench-Result-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Geekbench-Result.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">R\u00e9sultat Geekbench<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Nous obtenons des scores de 139 pour le monoc\u0153ur et de 470 pour le multic\u0153ur.  <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-antutu\">Antutu<\/h3>\n\n<p class=\"wp-block-paragraph\">Ensuite, Antutu effectue une s\u00e9rie de tests couvrant le CPU, le GPU, la RAM et le stockage.<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Antutu-Result.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Antutu-Result-1024x576.jpg\" alt=\"R&#xE9;sultat Antutu\" class=\"wp-image-27017\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Antutu-Result-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Antutu-Result-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Antutu-Result-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Antutu-Result-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Antutu-Result-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Antutu-Result-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Antutu-Result-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Antutu-Result.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">R\u00e9sultat Antutu<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Nous avons obtenu un score final de 101 393, ce qui est un bon r\u00e9sultat. Voici la r\u00e9partition des r\u00e9sultats.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-3dmark-mobile\">3DMark Mobile<\/h3>\n\n<p class=\"wp-block-paragraph\">Enfin, 3DMark mobile \u00e9value les performances combin\u00e9es du CPU et du GPU. Il n'est pas seulement adapt\u00e9 aux jeux, mais aussi \u00e0 des t\u00e2ches telles que le d\u00e9codage vid\u00e9o.<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-3DMark-Mobile-Result.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-3DMark-Mobile-Result-1024x576.jpg\" alt=\"R&#xE9;sultat 3DMark Mobile\" class=\"wp-image-27022\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-3DMark-Mobile-Result-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-3DMark-Mobile-Result-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-3DMark-Mobile-Result-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-3DMark-Mobile-Result-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-3DMark-Mobile-Result-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-3DMark-Mobile-Result-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-3DMark-Mobile-Result-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-3DMark-Mobile-Result.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">R\u00e9sultat 3DMark Mobile<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Nous avons obtenu un score de 596 pour le test Sling Shot et un score de 187 pour le test Wild Life. A titre de comparaison, il se situe \u00e0 peu pr\u00e8s dans la zone de performance de l'ordinateur de poche RG353V.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-video-playback\">Lecture vid\u00e9o<\/h3>\n\n<p class=\"wp-block-paragraph\">Une br\u00e8ve d\u00e9monstration de la lecture de la vid\u00e9o suit. Nous commen\u00e7ons par un fichier vid\u00e9o 4K et 8K dans KDPlayer. Les deux fonctionnent tr\u00e8s bien, sans aucune chute de cadre. Le bo\u00eetier <a href=\"https:\/\/droix.eu\/fr\/product\/droix-x4\/\" target=\"_blank\" rel=\"noreferrer noopener\">DroiX X4<\/a> IPTV peut d\u00e9coder des vid\u00e9os 8K sans probl\u00e8me, mais il les restitue en 4K.<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-8K-Video-Test.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-8K-Video-Test-1024x576.jpg\" alt=\"Test vid&#xE9;o DroiX X4 8K\" class=\"wp-image-27027\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-8K-Video-Test-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-8K-Video-Test-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-8K-Video-Test-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-8K-Video-Test-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-8K-Video-Test-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-8K-Video-Test-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-8K-Video-Test-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-8K-Video-Test.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Test vid\u00e9o DroiX X4 8K<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Et pour YouTube, nous diffusons une vid\u00e9o d'\u00e9valuation de DroiX 4K. La lecture se fait sans probl\u00e8me, les vid\u00e9os d\u00e9marrent rapidement et il n'y a pas de perte d'images.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-software\">Logiciel<\/h2>\n\n<p class=\"wp-block-paragraph\">La DroiX X4 Android TV box est livr\u00e9e avec Google Play Store, ce qui vous permet d'acc\u00e9der \u00e0 des millions d'applications. Vous pouvez t\u00e9l\u00e9charger et mettre \u00e0 jour n'importe quelle application sans aucun probl\u00e8me. Vous pouvez bien s\u00fbr installer des applications provenant d'autres sources. Il y a aussi une option dans les param\u00e8tres pour passer d'un appareil enracin\u00e9 \u00e0 un appareil non enracin\u00e9, vous n'avez m\u00eame pas besoin de red\u00e9marrer pour le faire, ce qui est g\u00e9nial !<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Software.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Software-1024x576.jpg\" alt=\"Logiciel DroiX X4\" class=\"wp-image-27032\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Software-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Software-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Software-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Software-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Software-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Software-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Software-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Software.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Logiciel DroiX X4<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Un certain nombre d'applications sont pr\u00e9install\u00e9es sur le DroiX X4, notamment les lecteurs multim\u00e9dias KDPlayer et Media Center, ainsi que les versions standard et mobile de YouTube. Parmi les applications habituelles, on trouve Google Chrome, un gestionnaire de fichiers et un logiciel d'installation d'applications.<\/p>\n\n<p class=\"wp-block-paragraph\">eShare est une application tr\u00e8s utile. Il vous permet de contr\u00f4ler votre DroiX X4 avec votre Android, iPhone ou iPad. Il vous suffit de t\u00e9l\u00e9charger l'<a href=\"https:\/\/eshare.app\/#once\" target=\"_blank\" rel=\"noreferrer noopener\">application eShare<\/a> sur votre appareil et de suivre les instructions pour vous connecter.<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-eShare-app.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-eShare-app-1024x576.jpg\" alt=\"DroiX X4 eShare app\" class=\"wp-image-27037\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-eShare-app-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-eShare-app-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-eShare-app-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-eShare-app-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-eShare-app-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-eShare-app-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-eShare-app-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-eShare-app.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">DroiX X4 eShare app<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Une fois connect\u00e9, vous pouvez l'utiliser comme une t\u00e9l\u00e9commande avec le curseur et la navigation normale. Vous pouvez \u00e9galement transf\u00e9rer des vid\u00e9os de votre t\u00e9l\u00e9phone vers la DroIX X4. Vous pouvez envoyer des photos et les manipuler. Et d'autres fonctions telles que la mise en miroir du t\u00e9l\u00e9phone et de l'appareil, qui permet d'afficher l'\u00e9cran du t\u00e9l\u00e9phone ou du X4 sur l'autre appareil. Il s'agit en quelque sorte d'un bureau \u00e0 distance.  <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-gaming-performance\">Performances des jeux<\/h2>\n\n<p class=\"wp-block-paragraph\">Dans le cadre de notre \u00e9valuation de la DroiX X4, nous v\u00e9rifions les performances de jeu. Vous pouvez transformer le <a href=\"https:\/\/droix.eu\/fr\/product\/droix-x4\/\" target=\"_blank\" rel=\"noreferrer noopener\">DroiX X4<\/a> en une bo\u00eete de jeu Android, et en un syst\u00e8me de jeu r\u00e9tro encore meilleur lorsqu'il est associ\u00e9 \u00e0 l'une de nos manettes de jeu <a href=\"https:\/\/droix.net\/blogs\/brand\/easysmx\/\" target=\"_blank\" rel=\"noreferrer noopener\">EasySMX<\/a>. Nous pr\u00e9f\u00e9rons l'<a href=\"https:\/\/droix.eu\/fr\/product\/easysmx-esm-9110\/\" target=\"_blank\" rel=\"noreferrer noopener\">ESM-9110<\/a>, mais les trois fonctionnent parfaitement avec le DroiX X4.<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-EasySMX-ESM-9110-controller.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-EasySMX-ESM-9110-controller-1024x576.jpg\" alt=\"Contr&#xF4;leur EasySMX ESM-9110\" class=\"wp-image-27042\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-EasySMX-ESM-9110-controller-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-EasySMX-ESM-9110-controller-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-EasySMX-ESM-9110-controller-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-EasySMX-ESM-9110-controller-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-EasySMX-ESM-9110-controller-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-EasySMX-ESM-9110-controller-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-EasySMX-ESM-9110-controller-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-EasySMX-ESM-9110-controller.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Contr\u00f4leur EasySMX ESM-9110<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Il existe de nombreux jeux Android natifs qui prennent en charge les manettes de jeu et qui rendent les jeux beaucoup plus agr\u00e9ables. Vous pr\u00e9f\u00e9rez jouer sur un grand \u00e9cran plut\u00f4t que sur un t\u00e9l\u00e9phone en appuyant sur des boutons \u00e0 l'\u00e9cran ?<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Grimvalor.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Grimvalor-1024x576.jpg\" alt=\"Jeu Android Grimvalor\" class=\"wp-image-27047\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Grimvalor-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Grimvalor-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Grimvalor-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Grimvalor-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Grimvalor-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Grimvalor-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Grimvalor-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-Grimvalor.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Jeu Android Grimvalor<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Nous avons essay\u00e9 un certain nombre de jeux et ceux dont les param\u00e8tres de la manette \u00e9taient compatibles ont tr\u00e8s bien fonctionn\u00e9. Ce que nous avons vraiment appr\u00e9ci\u00e9, c'est d'installer l'application de streaming Xbox Cloud et de jouer \u00e0 des jeux Windows AAA comme si nous \u00e9tions assis devant un PC ou une Xbox. Si vous disposez d'une vitesse d'Internet suffisante, vous n'aurez aucun probl\u00e8me \u00e0 regarder les jeux en streaming, sans d\u00e9calage ni artefacts.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-emulation-performance\">Performance de l'\u00e9mulation<\/h2>\n\n<p class=\"wp-block-paragraph\">Alors que la DroIX X4 Android box est d\u00e9cente pour les jeux, nous obtenons de tr\u00e8s bonnes performances pour les \u00e9mulateurs. Si vous souhaitez vous lancer rapidement dans le retro gaming, nous vous recommandons d'installer RetroArch. Nous avons un <a href=\"https:\/\/droix.net\/knowledge-base\/fr\/article\/retroarch\/\" target=\"_blank\" rel=\"noopener\" title=\"\">guide d'installation de RetroArch facile \u00e0 suivre ici.<\/a><\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-SNES-Emulator.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-SNES-Emulator-1024x576.jpg\" alt=\"Emulateur SNES - Pocky &amp;amp; Rocky\" class=\"wp-image-27052\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-SNES-Emulator-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-SNES-Emulator-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-SNES-Emulator-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-SNES-Emulator-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-SNES-Emulator-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-SNES-Emulator-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-SNES-Emulator-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-SNES-Emulator.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Emulateur SNES - Pocky &amp; Rocky<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Avec RetroArch, vous avez acc\u00e8s \u00e0 des dizaines de consoles et d'ordinateurs classiques, de l'Atari 2660 aux syst\u00e8mes plus modernes.<\/p>\n\n<p class=\"wp-block-paragraph\">Vous n'aurez aucun probl\u00e8me \u00e0 faire fonctionner toutes les consoles et ordinateurs 8-bit et 16-bit de ces \u00e9poques. Pour les autres syst\u00e8mes \u00e0 partir de cette zone, nous recommandons d'installer des applications s\u00e9par\u00e9es, car elles sont g\u00e9n\u00e9ralement plus performantes.<\/p>\n<div class=\"wp-block-image is-resized\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-GTA-Vice-City-Stories.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-GTA-Vice-City-Stories-1024x576.jpg\" alt=\"Emulateur PSP GTA Vice City Stories\" class=\"wp-image-27057\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-GTA-Vice-City-Stories-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-GTA-Vice-City-Stories-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-GTA-Vice-City-Stories-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-GTA-Vice-City-Stories-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-GTA-Vice-City-Stories-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-GTA-Vice-City-Stories-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-GTA-Vice-City-Stories-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2022\/10\/DroiX-X4-GTA-Vice-City-Stories.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Emulateur PSP GTA Vice City Stories<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Pour le PPSSPP, les r\u00e9sultats sont mitig\u00e9s. Les jeux les moins exigeants, ou ceux qui tournent \u00e0 30 FPS, ne devraient pas poser de probl\u00e8me. Pour les jeux les plus exigeants, vous devrez certainement utiliser le saut d'image pour que les jeux fonctionnent.<\/p>\n\n<h2 class=\"wp-block-heading\">O\u00f9 acheter le DroiX X4 ?<\/h2>\n\n<p class=\"wp-block-paragraph\">Vous pouvez en savoir plus et acheter votre <a href=\"https:\/\/droix.eu\/fr\/product\/droix-x4\/\" target=\"_blank\" rel=\"noreferrer noopener\">DroiX X4 ici<\/a>. C'est le meilleur bo\u00eetier TV Android disponible ! Ou parcourez notre gamme de <a href=\"https:\/\/droix.net\/blogs\/product-category\/android-gadgets\/android-tv-boxes\/\" target=\"_blank\" rel=\"noreferrer noopener\">bo\u00eetiers TV Android ici<\/a>.<\/p>\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-7d812b4c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/droix.eu\/fr\/product\/droix-x4\/\" style=\"background-color:#9fb526\" target=\"_blank\" rel=\"noreferrer noopener\">ACHETER DROIX X4 ICI<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">Voil\u00e0 qui conclut notre test du DroiX X4, en esp\u00e9rant qu'il vous aura \u00e9t\u00e9 utile. Laissez-nous savoir ce que vous pensez du DroiX X4 dans les commentaires, nous appr\u00e9cions toujours les r\u00e9actions !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans notre test du DroiX X4, nous examinons cette Android TV box avec une vue d'ensemble, des benchmarks pour la vid\u00e9o 4K et 8K, les jeux Android et le r\u00e9tro gaming.<\/p>\n","protected":false},"author":859,"featured_media":27079,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[211,389],"tags":[384,380],"class_list":["post-30047","post","type-post","status-publish","format-standard","has-post-thumbnail","category-critiques","category-appareils-android","tag-android-tv-box-fr","tag-droix-fr"],"_links":{"self":[{"href":"https:\/\/droix.net\/blogs\/fr\/wp-json\/wp\/v2\/posts\/30047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/blogs\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/droix.net\/blogs\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/droix.net\/blogs\/fr\/wp-json\/wp\/v2\/users\/859"}],"replies":[{"embeddable":true,"href":"https:\/\/droix.net\/blogs\/fr\/wp-json\/wp\/v2\/comments?post=30047"}],"version-history":[{"count":3,"href":"https:\/\/droix.net\/blogs\/fr\/wp-json\/wp\/v2\/posts\/30047\/revisions"}],"predecessor-version":[{"id":329079,"href":"https:\/\/droix.net\/blogs\/fr\/wp-json\/wp\/v2\/posts\/30047\/revisions\/329079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/droix.net\/blogs\/fr\/wp-json\/wp\/v2\/media\/27079"}],"wp:attachment":[{"href":"https:\/\/droix.net\/blogs\/fr\/wp-json\/wp\/v2\/media?parent=30047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/droix.net\/blogs\/fr\/wp-json\/wp\/v2\/categories?post=30047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/droix.net\/blogs\/fr\/wp-json\/wp\/v2\/tags?post=30047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}