{"id":349246,"date":"2025-11-07T14:07:15","date_gmt":"2025-11-07T14:07:15","guid":{"rendered":"https:\/\/droix.net\/blogs\/analise-da-ayaneo-flip-1s-ds-sera-esta-maquina-de-ecra-duplo-o-futuro-dos-jogos-portateis\/"},"modified":"2025-11-07T14:19:15","modified_gmt":"2025-11-07T14:19:15","slug":"analise-da-ayaneo-flip-1s-ds-sera-esta-maquina-de-ecra-duplo-o-futuro-dos-jogos-portateis","status":"publish","type":"post","link":"https:\/\/droix.net\/blogs\/pt-pt\/analise-da-ayaneo-flip-1s-ds-sera-esta-maquina-de-ecra-duplo-o-futuro-dos-jogos-portateis\/","title":{"rendered":"An\u00e1lise da AYANEO Flip 1S DS - Ser\u00e1 esta m\u00e1quina de ecr\u00e3 duplo o futuro dos jogos port\u00e1teis?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A AYANEO regressou, trazendo uma atualiza\u00e7\u00e3o empolgante ao PC de jogos port\u00e1til com ecr\u00e3 duplo que lan\u00e7ou no ano passado. Consequentemente, vamos descobrir na nossa an\u00e1lise do AYANEO Flip 1S DS quais as novas funcionalidades que o AYANEO 1S DS traz para os f\u00e3s de jogos com ecr\u00e3 duplo. <\/p>\n\n<h2 class=\"wp-block-heading\">V\u00eddeo de avalia\u00e7\u00e3o do AYANEO 1S DS<\/h2>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"AYANEO Flip 1S DS review: Ryzen AI 9 HX 370 Power + Dual Screen Magic! \ud83c\udfae\u2728\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/E0OxVerAC2s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<h2 class=\"wp-block-heading\">V\u00ea mais de perto: Desembala o AYANEO 1S DS<\/h2>\n\n<p class=\"wp-block-paragraph\">Come\u00e7amos a nossa an\u00e1lise do AYANEO 1S DS com uma inspe\u00e7\u00e3o minuciosa deste PC de jogos port\u00e1til. O AYANEO 1S DS mede aproximadamente 7,0 x 4,0 x 1,15 polegadas (18,0 x 10,2 x 2,93 cm). Al\u00e9m disso, pesa cerca de 655g (1,44 lbs).  <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/10\/AYANEO-Flip-1S-DS-Dimensions-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/10\/AYANEO-Flip-1S-DS-Dimensions-1024x576.jpg\" alt=\"AYANEO Flip 1S DS An&#xE1;lise das dimens&#xF5;es\" class=\"wp-image-346987\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/10\/AYANEO-Flip-1S-DS-Dimensions-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/10\/AYANEO-Flip-1S-DS-Dimensions-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/10\/AYANEO-Flip-1S-DS-Dimensions-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/10\/AYANEO-Flip-1S-DS-Dimensions-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/10\/AYANEO-Flip-1S-DS-Dimensions-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/10\/AYANEO-Flip-1S-DS-Dimensions-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/10\/AYANEO-Flip-1S-DS-Dimensions-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/10\/AYANEO-Flip-1S-DS-Dimensions.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Dimens\u00f5es do AYANEO Flip 1S DS<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">Ao abrir o AYANEO 1S DS, revela o seu ecr\u00e3 OLED 1080P de 7 polegadas localizado na parte superior. Este ecr\u00e3 impressionante suporta v\u00e1rias taxas de atualiza\u00e7\u00e3o, desde <a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/refresh-rate\/60hz\/\" target=\"_blank\" rel=\"noopener\" title=\"60Hz\">60Hz<\/a> at\u00e9 uns suaves <a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/refresh-rate\/144hz\/\" target=\"_blank\" rel=\"noopener\" title=\"144Hz\">144Hz<\/a>. Al\u00e9m disso, a dobradi\u00e7a \u00e9 bastante flex\u00edvel, permitindo a utiliza\u00e7\u00e3o de qualquer \u00e2ngulo, at\u00e9 180 graus.  <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Display-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347043\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Display-1024x576.jpg\" alt=\"Ecr&#xE3; superior AYANEO Flip 1S DS\" class=\"wp-image-347043\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Display-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Display-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Display-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Display-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Display-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Display-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Display-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Display.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Ecr\u00e3 superior AYANEO Flip 1S DS<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Display-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347015\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Display-1024x576.jpg\" alt=\"AYANEO Flip 1S DS Ecr&#xE3; inferior\" class=\"wp-image-347015\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Display-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Display-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Display-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Display-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Display-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Display-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Display-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Display.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">AYANEO Flip 1S DS Ecr\u00e3 inferior<\/figcaption><\/figure>\n<\/figure>\n\n<p class=\"wp-block-paragraph\">Na parte inferior, encontramos todos os controlos de jogo habituais. Estes incluem dois man\u00edpulos anal\u00f3gicos TMR, um D-Pad e bot\u00f5es de a\u00e7\u00e3o normais. <\/p>\n\n<p class=\"wp-block-paragraph\">Ao longo da parte inferior, uma variedade de controlos est\u00e3o convenientemente colocados na ponta dos teus dedos. Esta \u00e1rea inclui um controlo do modo de ecr\u00e3 inferior, um bot\u00e3o de jogo Xbox, bot\u00f5es de volume e um bot\u00e3o de alimenta\u00e7\u00e3o com um sensor de impress\u00f5es digitais integrado. Al\u00e9m disso, inclui tamb\u00e9m um rato \u00f3tico de dedo, um bot\u00e3o de sobreposi\u00e7\u00e3o AYA e bot\u00f5es dedicados do ambiente de trabalho.  <\/p>\n\n<p class=\"wp-block-paragraph\">No meio est\u00e1 o segundo ecr\u00e3. Trata-se de um painel IPS com 4,5 polegadas e uma resolu\u00e7\u00e3o de 1620&#215;1080. <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Side-View-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347099\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Side-View-1024x576.jpg\" alt=\"Vista lateral inferior do AYANEO Flip 1S DS\" class=\"wp-image-347099\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Side-View-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Side-View-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Side-View-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Side-View-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Side-View-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Side-View-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Side-View-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Bottom-Side-View.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Vista lateral inferior do AYANEO Flip 1S DS<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Side-View-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347127\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Side-View-1024x576.jpg\" alt=\"Vista lateral superior do AYANEO Flip 1S DS\" class=\"wp-image-347127\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Side-View-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Side-View-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Side-View-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Side-View-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Side-View-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Side-View-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Side-View-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Top-Side-View.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Vista lateral superior do AYANEO Flip 1S DS<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Textured-Grips-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347155\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Textured-Grips-1024x576.jpg\" alt=\"AYANEO Flip 1S DS Punhos com textura\" class=\"wp-image-347155\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Textured-Grips-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Textured-Grips-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Textured-Grips-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Textured-Grips-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Textured-Grips-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Textured-Grips-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Textured-Grips-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Textured-Grips.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">AYANEO Flip 1S DS Punhos com textura<\/figcaption><\/figure>\n<\/figure>\n\n<p class=\"wp-block-paragraph\">Ao olhares para a parte superior do AYANEO 1S DS, encontrar\u00e1s os controlos de ombro e de gatilho esquerdo e direito, bem como os bot\u00f5es macro. Tamb\u00e9m tens um leitor de cart\u00f5es micro SD coberto. Ao lado deste, tens duas portas USB 4 para perif\u00e9ricos de alta velocidade.  <\/p>\n\n<p class=\"wp-block-paragraph\">Por fim, a parte de tr\u00e1s do PC m\u00f3vel para jogos inclui dois punhos texturizados substitu\u00edveis. Um dos punhos \u00e9 rugoso, enquanto o outro tem uma textura mais ondulada. Podes alternar facilmente entre estas duas op\u00e7\u00f5es, dependendo da tua prefer\u00eancia pessoal.  <\/p>\n\n<h2 class=\"wp-block-heading\">Especifica\u00e7\u00f5es t\u00e9cnicas do AYANEO Flip 1S DS<\/h2>\n\n<p class=\"wp-block-paragraph\">Continuamos a nossa an\u00e1lise do AYANEO Flip 1S DS com um olhar sobre as especifica\u00e7\u00f5es t\u00e9cnicas<\/p>\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>CPU<\/strong><\/td><td>AMD <a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/processor-cpu-model\/amd-ryzen-7-8840u\/\" target=\"_blank\" rel=\"noopener\" title=\"Ryzen 7 8840U\">Ryzen 7 8840U<\/a><br\/>AMD <a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/processor-cpu-model\/ryzen-ai-9-hx-370\/\" target=\"_blank\" rel=\"noopener\" title=\"Ryzen AI 9 HX 370\">Ryzen AI 9 HX 370<\/a><\/td><\/tr><tr><td><strong>GPU<\/strong><\/td><td><a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/processor-cpu-brand\/amd\/\" target=\"_blank\" rel=\"noopener\" title=\"AMD\">AMD<\/a> <a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/graphics-gpu-model\/ryzen-7-8840u-radeon-780m\/\" target=\"_blank\" rel=\"noopener\" title=\"Radeon 780M\">Radeon 780M<\/a><br\/>AMD <a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/graphics-gpu-model\/ryzen-ai-9-hx-370-radeon-890m\/\" target=\"_blank\" rel=\"noopener\" title=\"Radeon 890M\">Radeon 890M<\/a><\/td><\/tr><tr><td><strong>RAM<\/strong><\/td><td>16GB\/32GB (modelos 8840U e HX 370)<br\/>64GB (apenas modelo HX 370) LPDDR5X 7500MT\/s<\/td><\/tr><tr><td><strong>ARMAZENAMENTO<\/strong><\/td><td>1TB \/ 2TB M.2 2230 PCIe 4.0 <\/td><\/tr><tr><td><strong>VISUALIZA\u00c7\u00d5ES<\/strong><\/td><td>7&#8243; <a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/display-type\/oled\/\" target=\"_blank\" rel=\"noopener\" title=\"OLED\">OLED<\/a> 1920&#215;1080 60Hz \/ <a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/refresh-rate\/90hz\/\" target=\"_blank\" rel=\"noopener\" title=\"90Hz\">90Hz<\/a> \/ <a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/refresh-rate\/120hz\/\" target=\"_blank\" rel=\"noopener\" title=\"120Hz\">120Hz<\/a> \/ 144Hz 315 PPI<br\/>4,5&#8243; IPS 1620&#215;1080 60Hz 433 PPI<\/td><\/tr><tr><td><strong>E\/S<\/strong><\/td><td><a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/i-o-usb\/2x-usb-4-0-type-c-40gb-s\/\" target=\"_blank\" rel=\"noopener\" title=\"2x USB 4\">2x USB 4<\/a><br\/><a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/storage-expansion\/1x-micro-sd-card-slot\/\" target=\"_blank\" rel=\"noopener\" title=\"1x Leitor de cart&#xF5;es Micro SD\">1x Leitor de cart\u00f5es Micro SD<\/a><br\/>1x Tomada para auscultadores de 3,5 mm<br\/>1x Rato \u00f3tico de dedo<\/td><\/tr><tr><td><strong>COMUNICA\u00c7\u00d5ES<\/strong><\/td><td>Wi-Fi <a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/wi-fi\/6e\/\" target=\"_blank\" rel=\"noopener\" title=\"6E\">6E<\/a><br\/>Bluetooth <a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/bluetooth\/5-3\/\" target=\"_blank\" rel=\"noopener\" title=\"5.3\">5.3<\/a><\/td><\/tr><tr><td><strong>BATERIA<\/strong><\/td><td>45Wh recarreg\u00e1vel<\/td><\/tr><tr><td><strong>SO<\/strong><\/td><td>Windows 11 Home<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"wp-block-paragraph\">Este computador port\u00e1til para jogos \u00e9 alimentado por uma bateria de 45Wh. A bateria suporta um carregamento PD de at\u00e9 65W e, o que \u00e9 mais importante, tamb\u00e9m suporta o carregamento bypass. <\/p>\n\n<p class=\"wp-block-paragraph\">Nos nossos testes, obtivemos cerca de 1 hora e 5 minutos de dura\u00e7\u00e3o da bateria. Este teste foi efectuado com o Cinebench a um TDP de 28W com luminosidade total. Esta dura\u00e7\u00e3o da bateria \u00e9 aproximadamente a mesma que a de outros dispositivos port\u00e1teis semelhantes, o que \u00e9 bastante bom. Isto \u00e9 especialmente verdade tendo em conta que o AYANEO 1S DS est\u00e1 a alimentar um ecr\u00e3 duplo.   <\/p>\n\n<h2 class=\"wp-block-heading\">Navegar no software de ecr\u00e3 duplo<\/h2>\n\n<p class=\"wp-block-paragraph\">Com o software <a href=\"https:\/\/droix.eu\/pt-pt\/product-attribute\/brands\/ayaneo\/\" target=\"_blank\" rel=\"noopener\" title=\"AYANEO\">AYANEO<\/a> incorporado, podes navegar atrav\u00e9s de v\u00e1rios separadores na parte inferior do segundo ecr\u00e3. Estes separadores podem ser utilizados para mostrar as estat\u00edsticas actuais do sistema, incluindo TDP, velocidade da ventoinha e utiliza\u00e7\u00e3o de recursos. O segundo ecr\u00e3 tamb\u00e9m te permite alterar as defini\u00e7\u00f5es. Inclui atalhos \u00fateis para os modos Extremo, Equilibrado e de poupan\u00e7a de energia.   <\/p>\n\n<h3 class=\"wp-block-heading\">Assistente r\u00e1pido e gest\u00e3o de aplica\u00e7\u00f5es<\/h3>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Quick-Assistant-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347211\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Quick-Assistant-1024x576.jpg\" alt=\"AYANEO Flip 1S DS Menu - Assistente r&#xE1;pido\" class=\"wp-image-347211\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Quick-Assistant-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Quick-Assistant-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Quick-Assistant-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Quick-Assistant-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Quick-Assistant-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Quick-Assistant-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Quick-Assistant-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Quick-Assistant.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Menu - Assistente r\u00e1pido<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Performance-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347183\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Performance-1024x576.jpg\" alt=\"AYANEO Flip 1S DS Menu - Desempenho\" class=\"wp-image-347183\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Performance-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Performance-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Performance-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Performance-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Performance-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Performance-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Performance-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Performance.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Menu - Desempenho<\/figcaption><\/figure>\n<\/figure>\n\n<p class=\"wp-block-paragraph\">A funcionalidade Assistente R\u00e1pido fornece \u00edcones grandes para fun\u00e7\u00f5es comuns. Por exemplo, podes alternar facilmente entre modos de ambiente de trabalho, tirar capturas de ecr\u00e3, alternar entre ecr\u00e3 inteiro e minimizar software. Al\u00e9m disso, a sec\u00e7\u00e3o \"Aplica\u00e7\u00e3o\" permite-te adicionar atalhos para as tuas aplica\u00e7\u00f5es mais utilizadas.  <\/p>\n\n<h3 class=\"wp-block-heading\">Funcionalidade de ecr\u00e3 duplo inteligente<\/h3>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Application-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347239\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Application-1024x576.jpg\" alt=\"AYANEO Flip 1S DS Menu - Aplica&#xE7;&#xE3;o\" class=\"wp-image-347239\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Application-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Application-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Application-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Application-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Application-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Application-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Application-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Application.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Menu - Aplica\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Mointor-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347267\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Mointor-1024x576.jpg\" alt=\"AYANEO Flip 1S DS Menu - Mointor\" class=\"wp-image-347267\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Mointor-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Mointor-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Mointor-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Mointor-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Mointor-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Mointor-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Mointor-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Menu-Mointor.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Menu - Monitor<\/figcaption><\/figure>\n<\/figure>\n\n<p class=\"wp-block-paragraph\">Uma fun\u00e7\u00e3o denominada \"ecr\u00e3 duplo inteligente\" foi concebida para te permitir mover facilmente o software atualmente aberto para o ecr\u00e3 inferior do AYANEO 1S DS. A partir daqui, podes abrir o teu browser, por exemplo, e depois mov\u00ea-lo para baixo. O software deve mostrar as aplica\u00e7\u00f5es que entram e saem do ecr\u00e3 inferior.  <\/p>\n\n<p class=\"wp-block-paragraph\">No entanto, por alguma raz\u00e3o, n\u00e3o consegui que o browser fosse apresentado desta forma automaticamente. Em vez disso, tive de mover manualmente as janelas para o ecr\u00e3 inferior. <\/p>\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o desempenho do AYANEO 1S DS nos jogos?<\/h2>\n\n<p class=\"wp-block-paragraph\">Como sabemos de muitos outros modelos de PCs compactos para jogos baseados na HX 370, o processador \u00e9 bastante capaz. Consegue executar jogos com resolu\u00e7\u00f5es e defini\u00e7\u00f5es gr\u00e1ficas decentes. Especificamente, a 1080P, podes geralmente jogar jogos com defini\u00e7\u00f5es m\u00e9dias a altas e atingir 60 FPS.  <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Elder-Scrolls-and-a-guide-on-the-browser-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347295\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Elder-Scrolls-and-a-guide-on-the-browser-1024x576.jpg\" alt=\"AYANEO Flip 1S DS Elder Scrolls e um guia sobre o browser\" class=\"wp-image-347295\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Elder-Scrolls-and-a-guide-on-the-browser-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Elder-Scrolls-and-a-guide-on-the-browser-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Elder-Scrolls-and-a-guide-on-the-browser-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Elder-Scrolls-and-a-guide-on-the-browser-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Elder-Scrolls-and-a-guide-on-the-browser-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Elder-Scrolls-and-a-guide-on-the-browser-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Elder-Scrolls-and-a-guide-on-the-browser-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Elder-Scrolls-and-a-guide-on-the-browser.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Elder Scrolls e um guia no browser<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Wuchang-and-some-retail-therapy-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347351\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Wuchang-and-some-retail-therapy-1024x576.jpg\" alt=\"AYANEO Flip 1S DS Wuchang e alguma terapia de retalho\" class=\"wp-image-347351\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Wuchang-and-some-retail-therapy-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Wuchang-and-some-retail-therapy-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Wuchang-and-some-retail-therapy-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Wuchang-and-some-retail-therapy-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Wuchang-and-some-retail-therapy-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Wuchang-and-some-retail-therapy-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Wuchang-and-some-retail-therapy-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Wuchang-and-some-retail-therapy.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Wuchang e uma terapia de compras<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Gaming-and-watching-a-video-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347323\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Gaming-and-watching-a-video-1024x576.jpg\" alt=\"AYANEO Flip 1S DS Jogos e visualiza&#xE7;&#xE3;o de um v&#xED;deo\" class=\"wp-image-347323\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Gaming-and-watching-a-video-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Gaming-and-watching-a-video-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Gaming-and-watching-a-video-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Gaming-and-watching-a-video-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Gaming-and-watching-a-video-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Gaming-and-watching-a-video-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Gaming-and-watching-a-video-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Gaming-and-watching-a-video.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Jogar e ver um v\u00eddeo<\/figcaption><\/figure>\n<\/figure>\n\n<p class=\"wp-block-paragraph\">Quanto ao segundo ecr\u00e3, podes us\u00e1-lo para ver um v\u00eddeo, seguir um guia ou manter o chat do Discord aberto. Podes at\u00e9 fazer umas compras na DROIX \ud83d\ude09 <\/p>\n\n<p class=\"wp-block-paragraph\">Realisticamente, no entanto, provavelmente ter\u00e1s o segundo ecr\u00e3 desligado a maior parte do tempo. Em alternativa, podes utiliz\u00e1-lo apenas para mostrar estat\u00edsticas de desempenho. <\/p>\n\n<h2 class=\"wp-block-heading\">Emula\u00e7\u00e3o e potencial de ecr\u00e3 duplo<\/h2>\n\n<p class=\"wp-block-paragraph\">O processador HX 370 tamb\u00e9m \u00e9 \u00f3timo para emula\u00e7\u00e3o. Consegue correr sistemas at\u00e9 \u00e0s consolas port\u00e1teis mais recentes com muito poucos problemas. Consequentemente, podemos tirar o m\u00e1ximo partido dos emuladores de consola port\u00e1til de ecr\u00e3 duplo, como o melonDS e o <a href=\"https:\/\/azahar-emu.org\/\" target=\"_blank\" rel=\"noopener nofollow\" title=\"Azahar\">Azahar<\/a>, no AYANEO 1S DS.  <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Azahar-3D-Dual-Screen-emulator-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347379\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Azahar-3D-Dual-Screen-emulator-1024x576.jpg\" alt=\"Emulador de ecr&#xE3; duplo AYANEO Flip 1S DS Azahar 3D\" class=\"wp-image-347379\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Azahar-3D-Dual-Screen-emulator-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Azahar-3D-Dual-Screen-emulator-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Azahar-3D-Dual-Screen-emulator-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Azahar-3D-Dual-Screen-emulator-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Azahar-3D-Dual-Screen-emulator-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Azahar-3D-Dual-Screen-emulator-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Azahar-3D-Dual-Screen-emulator-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Azahar-3D-Dual-Screen-emulator.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Emulador Azahar 3D Dual Screen<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-melonDS-Dual-Screen-emulator-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347407\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-melonDS-Dual-Screen-emulator-1024x576.jpg\" alt=\"AYANEO Flip 1S DS melonDS Emulador de ecr&#xE3; duplo\" class=\"wp-image-347407\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-melonDS-Dual-Screen-emulator-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-melonDS-Dual-Screen-emulator-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-melonDS-Dual-Screen-emulator-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-melonDS-Dual-Screen-emulator-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-melonDS-Dual-Screen-emulator-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-melonDS-Dual-Screen-emulator-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-melonDS-Dual-Screen-emulator-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-melonDS-Dual-Screen-emulator.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">emulador melonDS Dual Screen<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Vita3K-Emulator-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"347435\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Vita3K-Emulator-1024x576.jpg\" alt=\"Emulador AYANEO Flip 1S DS Vita3K\" class=\"wp-image-347435\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Vita3K-Emulator-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Vita3K-Emulator-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Vita3K-Emulator-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Vita3K-Emulator-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Vita3K-Emulator-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Vita3K-Emulator-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Vita3K-Emulator-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Vita3K-Emulator.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Emulador Vita3K<\/figcaption><\/figure>\n<\/figure>\n\n<p class=\"wp-block-paragraph\">Estes emuladores de computador de m\u00e3o de ecr\u00e3 duplo requerem um pouco de configura\u00e7\u00e3o. Isto \u00e9 necess\u00e1rio para tirares partido dos dois ecr\u00e3s deste computador de m\u00e3o para jogos. O processo envolve a altera\u00e7\u00e3o de algumas op\u00e7\u00f5es de menu para criar uma segunda janela. Esta janela deve ent\u00e3o ser exibida no segundo ecr\u00e3.   <\/p>\n\n<p class=\"wp-block-paragraph\">Deves ter em aten\u00e7\u00e3o que esta configura\u00e7\u00e3o n\u00e3o \u00e9 perfeita em todos os casos. Poder\u00e1s necessitar de software de terceiros para que o segundo ecr\u00e3 emulado seja verdadeiramente de ecr\u00e3 inteiro. <\/p>\n\n<h2 class=\"wp-block-heading\">Considera\u00e7\u00f5es finais: O nosso veredito sobre o AYANEO 1S DS<\/h2>\n\n<p class=\"wp-block-paragraph\">O AYANEO 1S DS apresenta algumas melhorias decentes em rela\u00e7\u00e3o ao modelo original AYANEO DS. Se eras f\u00e3 do original, ent\u00e3o vais sem d\u00favida adorar o AYANEO 1S DS. <\/p>\n\n<p class=\"wp-block-paragraph\">O novo e maior segundo ecr\u00e3 torna tudo muito mais f\u00e1cil de utilizar e visualizar. Claro que o processador mais r\u00e1pido \u00e9 sempre uma adi\u00e7\u00e3o bem-vinda. <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Tony-Hawks-Pro-Skater-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Tony-Hawks-Pro-Skater-1024x576.jpg\" alt=\"AYANEO Flip 1S DS Tony Hawks Pro Skater\" class=\"wp-image-347463\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Tony-Hawks-Pro-Skater-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Tony-Hawks-Pro-Skater-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Tony-Hawks-Pro-Skater-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Tony-Hawks-Pro-Skater-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Tony-Hawks-Pro-Skater-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Tony-Hawks-Pro-Skater-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Tony-Hawks-Pro-Skater-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/AYANEO-Flip-1S-DS-Tony-Hawks-Pro-Skater.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Tony Hawks Pro Skater<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">No entanto, a quest\u00e3o principal \u00e9: precisas mesmo de uma consola port\u00e1til de ecr\u00e3 duplo? Se passas muito tempo a jogar em emuladores de ecr\u00e3 duplo ou a consultar frequentemente guias de jogos, ent\u00e3o a resposta \u00e9 claramente sim. <\/p>\n\n<p class=\"wp-block-paragraph\">Caso contr\u00e1rio, \u00e9 prov\u00e1vel que utilizes o segundo ecr\u00e3 durante alguns dias e depois o ignores quando a novidade passar. Neste caso, consideraria qualquer outro dispositivo port\u00e1til baseado no HX 370 como uma alternativa vi\u00e1vel. <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/Are-two-displays-useful-for-you-1024x576.jpg\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/Are-two-displays-useful-for-you-1024x576.jpg\" alt=\"Os dois ecr&#xE3;s s&#xE3;o &#xFA;teis para ti?\" class=\"wp-image-347491\" srcset=\"https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/Are-two-displays-useful-for-you-1024x576.jpg 1024w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/Are-two-displays-useful-for-you-300x169.jpg 300w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/Are-two-displays-useful-for-you-768x432.jpg 768w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/Are-two-displays-useful-for-you-1536x864.jpg 1536w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/Are-two-displays-useful-for-you-450x253.jpg 450w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/Are-two-displays-useful-for-you-780x439.jpg 780w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/Are-two-displays-useful-for-you-1600x900.jpg 1600w, https:\/\/droix.net\/blogs\/wp-content\/uploads\/2025\/11\/Are-two-displays-useful-for-you.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Os dois ecr\u00e3s s\u00e3o \u00fateis para ti?<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\">N\u00e3o estamos a vender o AYANEO 1S DS na DROIX. No entanto, temos em stock outros <a href=\"https:\/\/droix.eu\/pt-pt\/product-category\/gaming-handheld\/handheld-gaming-pcs\/\" target=\"_blank\" rel=\"noopener\" title=\"PCs port&#xE1;teis para jogos\">PCs de jogos port\u00e1teis<\/a>, incluindo o excelente <a href=\"https:\/\/droix.eu\/pt-pt\/product\/ayaneo-3\/\" target=\"_blank\" rel=\"noopener\" title=\"AYANEO 3\">AYANEO 3<\/a>. <\/p>\n\n<p class=\"wp-block-paragraph\">Assim terminamos a nossa an\u00e1lise do AYANEO 1S DS. Esperamos que lhe tenha sido \u00fatil. Se tiveres alguma d\u00favida, n\u00e3o hesites em perguntar nos coment\u00e1rios abaixo, e teremos todo o gosto em responder.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A nossa an\u00e1lise detalhada do AYANEO Flip 1S DS abrange o desempenho nos jogos, a dura\u00e7\u00e3o da bateria e a funcionalidade de ecr\u00e3 duplo. Ser\u00e1 que esta poderosa consola port\u00e1til vale o pre\u00e7o elevado?   <\/p>\n","protected":false},"author":859,"featured_media":347883,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[896,898,902],"tags":[2555,7036,1995,3181],"class_list":["post-349246","post","type-post","status-publish","format-standard","has-post-thumbnail","category-comentarios-pt-pt","category-android-devices-pt-pt","category-portateis-para-jogos-retro-pt-pt","tag-android-pt-pt","tag-flip-1s-ds","tag-janelas-pt-pt","tag-pc-de-jogos-portatil"],"_links":{"self":[{"href":"https:\/\/droix.net\/blogs\/pt-pt\/wp-json\/wp\/v2\/posts\/349246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/blogs\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/droix.net\/blogs\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/droix.net\/blogs\/pt-pt\/wp-json\/wp\/v2\/users\/859"}],"replies":[{"embeddable":true,"href":"https:\/\/droix.net\/blogs\/pt-pt\/wp-json\/wp\/v2\/comments?post=349246"}],"version-history":[{"count":1,"href":"https:\/\/droix.net\/blogs\/pt-pt\/wp-json\/wp\/v2\/posts\/349246\/revisions"}],"predecessor-version":[{"id":349249,"href":"https:\/\/droix.net\/blogs\/pt-pt\/wp-json\/wp\/v2\/posts\/349246\/revisions\/349249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/droix.net\/blogs\/pt-pt\/wp-json\/wp\/v2\/media\/347883"}],"wp:attachment":[{"href":"https:\/\/droix.net\/blogs\/pt-pt\/wp-json\/wp\/v2\/media?parent=349246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/droix.net\/blogs\/pt-pt\/wp-json\/wp\/v2\/categories?post=349246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/droix.net\/blogs\/pt-pt\/wp-json\/wp\/v2\/tags?post=349246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}