{"id":4246,"count":1,"description":"","link":"https:\/\/droix.net\/knowledge-base\/da\/device\/rg353-series-android\/","name":"RG353 Series (Android)","slug":"rg353-series-android","taxonomy":"kb_device","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/droix.net\/knowledge-base\/da\/wp-json\/wp\/v2\/kb_device\/4246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/knowledge-base\/da\/wp-json\/wp\/v2\/kb_device"}],"about":[{"href":"https:\/\/droix.net\/knowledge-base\/da\/wp-json\/wp\/v2\/taxonomies\/kb_device"}],"wp:post_type":[{"href":"https:\/\/droix.net\/knowledge-base\/da\/wp-json\/wp\/v2\/kb?kb_device=4246"},{"href":"https:\/\/droix.net\/knowledge-base\/da\/wp-json\/wp\/v2\/droix-resources?kb_device=4246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}