{"id":4201,"count":2,"description":"","link":"https:\/\/droix.net\/knowledge-base\/en-gb\/device\/rg350p\/","name":"RG350P","slug":"rg350p","taxonomy":"kb_device","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/droix.net\/knowledge-base\/en-gb\/wp-json\/wp\/v2\/kb_device\/4201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/knowledge-base\/en-gb\/wp-json\/wp\/v2\/kb_device"}],"about":[{"href":"https:\/\/droix.net\/knowledge-base\/en-gb\/wp-json\/wp\/v2\/taxonomies\/kb_device"}],"wp:post_type":[{"href":"https:\/\/droix.net\/knowledge-base\/en-gb\/wp-json\/wp\/v2\/kb?kb_device=4201"},{"href":"https:\/\/droix.net\/knowledge-base\/en-gb\/wp-json\/wp\/v2\/droix-resources?kb_device=4201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}