{"id":4186,"count":42,"description":"","link":"https:\/\/droix.net\/knowledge-base\/hu\/device\/gpd-win-4-2022-6800u\/","name":"GPD WIN 4 2022 (6800U)","slug":"gpd-win-4-2022-6800u","taxonomy":"kb_device","parent":4323,"meta":[],"_links":{"self":[{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/kb_device\/4186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/kb_device"}],"about":[{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/taxonomies\/kb_device"}],"up":[{"embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/kb_device\/4323"}],"wp:post_type":[{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/kb?kb_device=4186"},{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/droix-resources?kb_device=4186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}