{"id":4243,"count":4,"description":"","link":"https:\/\/droix.net\/knowledge-base\/hu\/device\/rg353\/","name":"RG353","slug":"rg353","taxonomy":"kb_device","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/kb_device\/4243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/kb_device"}],"about":[{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/taxonomies\/kb_device"}],"wp:post_type":[{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/kb?kb_device=4243"},{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/droix-resources?kb_device=4243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}