{"id":4361,"count":1,"description":"","link":"https:\/\/droix.net\/knowledge-base\/hu\/device\/onexplayer-mini-1195g7\/","name":"1195G7","slug":"onexplayer-mini-1195g7","taxonomy":"kb_device","parent":4355,"meta":[],"_links":{"self":[{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/kb_device\/4361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/kb_device"}],"about":[{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/taxonomies\/kb_device"}],"up":[{"embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/kb_device\/4355"}],"wp:post_type":[{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/kb?kb_device=4361"},{"href":"https:\/\/droix.net\/knowledge-base\/hu\/wp-json\/wp\/v2\/droix-resources?kb_device=4361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}