{"id":27808,"date":"2021-11-20T19:57:21","date_gmt":"2021-11-20T19:57:21","guid":{"rendered":"https:\/\/droix.net\/knowledge-base\/article\/come-eseguire-il-re-flash-di-gpd-win-3-oppure-come-installare-windows-su-gpd-win-3\/"},"modified":"2023-10-18T16:54:17","modified_gmt":"2023-10-18T15:54:17","slug":"come-eseguire-il-re-flash-di-gpd-win-3-oppure-come-installare-windows-su-gpd-win-3","status":"publish","type":"kb","link":"https:\/\/droix.net\/knowledge-base\/it\/article\/come-eseguire-il-re-flash-di-gpd-win-3-oppure-come-installare-windows-su-gpd-win-3\/","title":{"rendered":"Come eseguire il re-flash di GPD Win 3 (oppure: come installare Windows su GPD Win 3)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quindi hai provato a fare un reset di fabbrica, ma non ha risolto il problema? Il passo successivo per la risoluzione dei problemi del GPD Win 3 consiste nel flashare nuovamente il firmware del dispositivo. (O in altre parole: reinstallare Windows sul GPD Win 3).<\/p>\n\n<p class=\"wp-block-paragraph\">\u00c8 necessario:<\/p>\n\n<ul class=\"wp-block-list\"><li>Un&#8217;unit\u00e0 flash USB da 16 GB (o superiore)<\/li><li>Un PC in grado di scaricare file<\/li><\/ul>\n\n<p class=\"has-vivid-red-color has-text-color wp-block-paragraph\"><strong>DISCLAIMER: questa operazione rimuover\u00e0 tutti i dati dal GPD Win 3. Eseguire il backup dei dati o dei file che non si desidera perdere.<\/strong><\/p>\n\n<hr class=\"wp-block-separator is-style-wide\" \/>\n\n<h2 class=\"wp-block-heading\" id=\"h-step-1-prepare-a-bootable-usb\">Passo 1: Preparare una USB avviabile<\/h2>\n\n<p class=\"wp-block-paragraph\">Il primo passo consiste nel preparare l&#8217;USB da utilizzare per la reinstallazione. Ci\u00f2 avviene tramite la <a href=\"https:\/\/www.windowscentral.com\/how-format-usb-flash-drive-windows-10\" class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">formattazione dell&#8217;unit\u00e0 USB.<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Il modo in cui si esegue questa operazione non \u00e8 particolarmente importante (si pu\u00f2 utilizzare il sistema di formattazione dei file integrato in Window o un&#8217;applicazione di terze parti), tuttavia \u00e8 importante assicurarsi che due parametri siano corretti:<\/p>\n\n<ul class=\"wp-block-list\"><li>La partizione deve essere chiamata &#8220;WINPE\".<\/li><li>La partizione deve essere in formato <a href=\"https:\/\/en.wikipedia.org\/wiki\/NTFS\" class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">NTFS <\/a>.<\/li><\/ul>\n\n<p class=\"wp-block-paragraph\">Se uno di questi parametri non \u00e8 soddisfatto, l&#8217;USB non sar\u00e0 avviabile.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-step-2-download-the-files-for-the-gpd-win-3\">Passo 2: Scaricare i file per GPD Win 3<\/h2>\n\n<p class=\"wp-block-paragraph\">Per prima cosa \u00e8 necessario scaricare il firmware attuale. Avete due possibilit\u00e0:<\/p>\n\n<p class=\"wp-block-paragraph\">\u00c8 possibile scaricare il firmware cos\u00ec com&#8217;\u00e8, nel modo in cui GPD lo fornisce. Ecco il link: <a href=\"https:\/\/go.droix.net\/GPD-WIN-3-FW-FILES\" class=\"rank-math-link\">https:\/\/go.droix.net\/GPD-WIN-3-FW-FILES<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Oppure potete scaricare un file di immagine gi\u00e0 pronto da noi. Ecco il link: <a href=\"https:\/\/go.droix.net\/GPD-WIN-3-FW-IMG\" class=\"rank-math-link\">https:\/\/go.droix.net\/GPD-WIN-3-FW-IMG<\/a><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-step-3a-copy-the-files\">Passo 3a: copiare i file<\/h2>\n\n<p class=\"wp-block-paragraph\">Se i file del firmware sono stati scaricati cos\u00ec come sono, \u00e8 sufficiente copiare i file del firmware nella root dell&#8217;unit\u00e0 USB.  <\/p>\n\n<p class=\"wp-block-paragraph\">Per prima cosa, estrarre il file zip scaricato. \u00c8 possibile utilizzare gli <a href=\"https:\/\/www.howtogeek.com\/668409\/how-to-zip-and-unzip-files-on-windows-10\/\" class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">strumenti nativi di Windows<\/a> oppure scaricare uno strumento di terze parti (suggeriamo <a href=\"https:\/\/www.7-zip.org\/\" class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">7zip<\/a>).<\/p>\n\n<p class=\"wp-block-paragraph\">Una volta estratti tutti i file, fare clic con il pulsante destro del mouse su Copia, quindi spostarsi sull&#8217;unit\u00e0 USB e fare clic con il pulsante destro del mouse su Incolla. (Potete anche fare CTRL+C -&gt; CTRL+V, oppure tagliare e incollare, come preferite).<\/p>\n\n<p class=\"wp-block-paragraph\">Una volta copiato, il contenuto della chiavetta USB dovrebbe essere simile a questo:<\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/droix.net\/knowledge-base\/it\/wp-content\/uploads\/sites\/3\/2021\/11\/explorer_jwfj4CgMyk.jpg\"><img decoding=\"async\" src=\"https:\/\/droix.net\/knowledge-base\/it\/wp-content\/uploads\/sites\/3\/2021\/11\/explorer_jwfj4CgMyk.jpg\" alt=\"Win 3 File USB\" class=\"wp-image-21326\" width=\"328\" height=\"388\"\/><\/a><figcaption>Non importa se i PDF sono presenti o meno.<\/figcaption><\/figure><\/div>\n\n<p class=\"wp-block-paragraph\">L&#8217;USB \u00e8 ora pronta per il re-flash. \u00c8 possibile saltare il passaggio 3b, poich\u00e9 riguarda<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-step-3b-flash-the-usb\">Passo 3b: Eseguire il flashing dell&#8217;USB<\/h2>\n\n<p class=\"wp-block-paragraph\">Se avete scaricato il file immagine che abbiamo preparato, dovrete anche scaricare uno strumento di flashing USB. Personalmente preferiamo <a href=\"https:\/\/sourceforge.net\/projects\/win32diskimager\/\" class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">Win32 Disk Imager<\/a>, ma esistono alternative come <a href=\"https:\/\/rufus.ie\/en\/\" class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">Rufus<\/a> o <a href=\"https:\/\/www.tweaking4all.com\/software\/macosx-software\/applepi-baker-v2\/\" class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">ApplePi Baker<\/a> (per gli utenti Macintosh).<\/p>\n\n<p class=\"wp-block-paragraph\">Win32 Disk Imager \u00e8 uno strumento leggero, potente e facile da usare per creare file .img da USB.<\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/droix.net\/knowledge-base\/it\/wp-content\/uploads\/sites\/3\/2021\/11\/1.jpg\" alt=\"1.jpg\" width=\"424\" height=\"328\"\/><\/figure><\/div>\n\n<p class=\"wp-block-paragraph\">Assicurarsi che l&#8217;unit\u00e0 USB sia inserita e che sia stato scaricato il file immagine.<\/p>\n\n<p class=\"wp-block-paragraph\">In &#8220;Dispositivo\", selezionare la lettera di unit\u00e0 corrispondente all&#8217;unit\u00e0 USB. Se nel computer \u00e8 presente un solo disco rigido\/un&#8217;unit\u00e0 a stato solido, all&#8217;unit\u00e0 USB verr\u00e0 probabilmente assegnata automaticamente la lettera D:\\ , ma verificare!<\/p>\n\n<p class=\"wp-block-paragraph\">Alla voce &#8220;File immagine\", navigare fino all&#8217;immagine scaricata in precedenza. Non importa dove viene salvato, purch\u00e9 sia possibile trovarlo (e non verr\u00e0 spostato durante questo processo).<\/p>\n\n<p class=\"wp-block-paragraph\">Quindi, fare clic su &#8220;Scrivi\" e il processo avr\u00e0 inizio. Questa operazione richieder\u00e0 probabilmente dai 30 ai 60 minuti, a seconda della velocit\u00e0 del computer e delle porte USB collegate (nel frattempo \u00e8 possibile utilizzare il PC per altre attivit\u00e0, assicurandosi solo di non scollegare l&#8217;unit\u00e0 USB, aggiungere\/rimuovere file all&#8217;unit\u00e0 USB o chiudere l&#8217;applicazione).<\/p>\n\n<p class=\"wp-block-paragraph\">Quando la barra \u00e8 piena e viene visualizzato il popup che informa che l&#8217;imaging \u00e8 stato completato, \u00e8 possibile rimuovere l&#8217;unit\u00e0 USB.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-step-4-boot-into-the-usb-on-the-gpd-win-3\">Fase 4: avvio della USB sul GPD Win 3<\/h2>\n\n<p class=\"wp-block-paragraph\">Infine, \u00e8 necessario avviare la USB creata in uno dei due passaggi precedenti.<\/p>\n\n<p class=\"wp-block-paragraph\">A tal fine, inserire l&#8217;USB nella porta USB situata nella parte superiore del GPD Win 3. Quindi accendere il dispositivo e premere ripetutamente il tasto F7 per accedere al menu di avvio.<\/p>\n\n<p class=\"wp-block-paragraph\">Tuttavia, abbiamo riscontrato un&#8217;incoerenza a causa della velocit\u00e0 di avvio del dispositivo (che rende difficile l&#8217;accesso alla finestra). Se non \u00e8 possibile farlo, \u00e8 possibile entrare in Windows, aprire il menu di avvio e tenere premuto il tasto SHIFT mentre si seleziona &#8220;Riavvia\".<\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/droix.net\/knowledge-base\/it\/wp-content\/uploads\/sites\/3\/2021\/11\/msedge_PhWRa3myOZ.jpg\"><img decoding=\"async\" src=\"https:\/\/droix.net\/knowledge-base\/it\/wp-content\/uploads\/sites\/3\/2021\/11\/msedge_PhWRa3myOZ.jpg\" alt=\"Accesso alle opzioni di avvio avanzate di Windows 10\" class=\"wp-image-21328\" width=\"456\" height=\"408\"\/><\/a><figcaption>Tenere premuto shift mentre si seleziona &#8220;Riavvia\" per accedere alle opzioni di avvio avanzato di Windows 10.<\/figcaption><\/figure><\/div>\n\n<p class=\"wp-block-paragraph\">Selezionare &#8220;Usa una periferica\" dal menu visualizzato, quindi selezionare la periferica corrispondente all&#8217;USB utilizzata. Ad esempio, se avete usato una USB Kingston, potrebbe chiamarsi &#8220;Kingston DataTraveller\".<\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/droix.net\/knowledge-base\/it\/wp-content\/uploads\/sites\/3\/2021\/11\/IMG_20210525_123358624_HDR-1.jpg\"><img decoding=\"async\" src=\"https:\/\/droix.net\/knowledge-base\/it\/wp-content\/uploads\/sites\/3\/2021\/11\/IMG_20210525_123358624_HDR-1-1024x768.jpg\" alt=\"Immagine di recupero di Win 3 2\" class=\"wp-image-20538\" width=\"491\" height=\"368\"\/><\/a><\/figure><\/div>\n\n<p class=\"wp-block-paragraph\">Il processo di reinstallazione proceder\u00e0 automaticamente. Verr\u00e0 visualizzata un&#8217;interfaccia a riga di comando su sfondo blu come questa, mentre il sistema esegue le operazioni necessarie per cancellare il dispositivo e reinstallare Windows.<\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/droix.net\/knowledge-base\/it\/wp-content\/uploads\/sites\/3\/2021\/11\/win3_installation.jpg\"><img decoding=\"async\" src=\"https:\/\/droix.net\/knowledge-base\/it\/wp-content\/uploads\/sites\/3\/2021\/11\/win3_installation-1024x768.jpg\" alt=\"Schermata di reinstallazione di GPD Win 3\" class=\"wp-image-21401\" width=\"487\" height=\"366\"\/><\/a><figcaption>Se vedete qualcosa di simile, siete a posto. Assicuratevi che abbia una carica sufficiente e lasciatelo stare.<\/figcaption><\/figure><\/div>\n\n<p class=\"wp-block-paragraph\">Una volta completato, il sistema si riavvier\u00e0 automaticamente in una nuova installazione di Windows (non si spegner\u00e0 dopo l&#8217;installazione)!<\/p>\n\n<p class=\"wp-block-paragraph\">Ora il sistema \u00e8 stato sottoposto a un nuovo flash. Godetevi la vostra nuova installazione di Windows!<\/p>\n\n<hr class=\"wp-block-separator is-style-wide\" \/>\n\n<p class=\"wp-block-paragraph\">Grazie per aver letto fin qui. Per ulteriori suggerimenti, trucchi e guide relativi a GPD Win 3, consultate regolarmente il nostro blog per gli ultimi aggiornamenti! Se siete interessati all&#8217;acquisto di un GPD Win 3, consultate il nostro sito principale, dove attualmente sono disponibili entrambe le versioni del GPD Win 3!<\/p>\n\n<p class=\"wp-block-paragraph\">Alla prossima volta!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Volete reinstallare Windows sul vostro GPD Win 3? Non cercate altro che questa guida!<\/p>\n","protected":false},"author":7,"featured_media":14581,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"kbtopic":[280,385,397,340],"kbtag":[641],"kb_category":[4296],"kb_brand":[4155],"kb_device":[4168],"kb_section":[4313],"kb_learn":[4302],"class_list":["post-27808","kb","type-kb","status-publish","has-post-thumbnail","hentry","kbtopic-hardware","kbtopic-windows-it","kbtopic-windows-windows-it","kbtopic-windows-gaming-handhelds","kbtag-gpd-win-3-it","kb_category-windows-handhelds","kb_brand-gpd","kb_device-gpd-win-3","kb_section-os-software","kb_learn-windows"],"_links":{"self":[{"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kb\/27808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kb"}],"about":[{"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/types\/kb"}],"author":[{"embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/comments?post=27808"}],"version-history":[{"count":0,"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kb\/27808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/media\/14581"}],"wp:attachment":[{"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/media?parent=27808"}],"wp:term":[{"taxonomy":"kbtopic","embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kbtopic?post=27808"},{"taxonomy":"kbtag","embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kbtag?post=27808"},{"taxonomy":"kb_category","embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kb_category?post=27808"},{"taxonomy":"kb_brand","embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kb_brand?post=27808"},{"taxonomy":"kb_device","embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kb_device?post=27808"},{"taxonomy":"kb_section","embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kb_section?post=27808"},{"taxonomy":"kb_learn","embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kb_learn?post=27808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}