{"id":4360,"count":1,"description":"","link":"https:\/\/droix.net\/knowledge-base\/it\/device\/onexplayer-mini-1260p-5800u\/","name":"1260P \/ 5800U","slug":"onexplayer-mini-1260p-5800u","taxonomy":"kb_device","parent":4355,"meta":[],"_links":{"self":[{"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kb_device\/4360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kb_device"}],"about":[{"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/taxonomies\/kb_device"}],"up":[{"embeddable":true,"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kb_device\/4355"}],"wp:post_type":[{"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/kb?kb_device=4360"},{"href":"https:\/\/droix.net\/knowledge-base\/it\/wp-json\/wp\/v2\/droix-resources?kb_device=4360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}