{"id":4301,"count":297,"description":"Docks, eGPUs, chargers, gamepads and portable monitors.","link":"https:\/\/droix.net\/knowledge-base\/no\/category\/accessories\/","name":"Accessories &amp; Gamepads","slug":"accessories","taxonomy":"kb_category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/droix.net\/knowledge-base\/no\/wp-json\/wp\/v2\/kb_category\/4301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/knowledge-base\/no\/wp-json\/wp\/v2\/kb_category"}],"about":[{"href":"https:\/\/droix.net\/knowledge-base\/no\/wp-json\/wp\/v2\/taxonomies\/kb_category"}],"wp:post_type":[{"href":"https:\/\/droix.net\/knowledge-base\/no\/wp-json\/wp\/v2\/kb?kb_category=4301"},{"href":"https:\/\/droix.net\/knowledge-base\/no\/wp-json\/wp\/v2\/droix-resources?kb_category=4301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}