{"id":4340,"count":4,"description":"","link":"https:\/\/droix.net\/knowledge-base\/sk\/device\/retroid-pocket-2-plus\/","name":"Retroid Pocket 2 Plus","slug":"retroid-pocket-2-plus","taxonomy":"kb_device","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/droix.net\/knowledge-base\/sk\/wp-json\/wp\/v2\/kb_device\/4340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/knowledge-base\/sk\/wp-json\/wp\/v2\/kb_device"}],"about":[{"href":"https:\/\/droix.net\/knowledge-base\/sk\/wp-json\/wp\/v2\/taxonomies\/kb_device"}],"wp:post_type":[{"href":"https:\/\/droix.net\/knowledge-base\/sk\/wp-json\/wp\/v2\/kb?kb_device=4340"},{"href":"https:\/\/droix.net\/knowledge-base\/sk\/wp-json\/wp\/v2\/droix-resources?kb_device=4340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}