{"id":4320,"count":2,"description":"","link":"https:\/\/droix.net\/knowledge-base\/sl\/device\/onexplayer-onexfly\/","name":"ONEXPLAYER ONEXFLY","slug":"onexplayer-onexfly","taxonomy":"kb_device","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/droix.net\/knowledge-base\/sl\/wp-json\/wp\/v2\/kb_device\/4320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/knowledge-base\/sl\/wp-json\/wp\/v2\/kb_device"}],"about":[{"href":"https:\/\/droix.net\/knowledge-base\/sl\/wp-json\/wp\/v2\/taxonomies\/kb_device"}],"wp:post_type":[{"href":"https:\/\/droix.net\/knowledge-base\/sl\/wp-json\/wp\/v2\/kb?kb_device=4320"},{"href":"https:\/\/droix.net\/knowledge-base\/sl\/wp-json\/wp\/v2\/droix-resources?kb_device=4320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}