{"id":4231,"count":1,"description":"","link":"https:\/\/droix.net\/knowledge-base\/sv\/device\/anbernic-rg351p-m-odroid-go-advance-odroid-go-super\/","name":"Anbernic RG351P\/M, ODROID Go Advance, ODROID Go Super","slug":"anbernic-rg351p-m-odroid-go-advance-odroid-go-super","taxonomy":"kb_device","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/droix.net\/knowledge-base\/sv\/wp-json\/wp\/v2\/kb_device\/4231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/droix.net\/knowledge-base\/sv\/wp-json\/wp\/v2\/kb_device"}],"about":[{"href":"https:\/\/droix.net\/knowledge-base\/sv\/wp-json\/wp\/v2\/taxonomies\/kb_device"}],"wp:post_type":[{"href":"https:\/\/droix.net\/knowledge-base\/sv\/wp-json\/wp\/v2\/kb?kb_device=4231"},{"href":"https:\/\/droix.net\/knowledge-base\/sv\/wp-json\/wp\/v2\/droix-resources?kb_device=4231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}